{"id":94,"count":1,"description":"","link":"https:\/\/yosigo.ugr.es\/it\/course-tag\/bases-de-datos-relacionales\/","name":"database relazionali","slug":"database-relazionali","taxonomy":"ld_course_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>bases de datos relacionales archivos - #YoSigoUGR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yosigo.ugr.es\/it\/etichetta-del-corso\/database-relazionali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"bases de datos relacionales archivos - #YoSigoUGR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yosigo.ugr.es\/it\/etichetta-del-corso\/database-relazionali\/\" \/>\n<meta property=\"og:site_name\" content=\"#YoSigoUGR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/yosigo.ugr.es\\\/fr\\\/etiquette-de-cours\\\/les-bases-de-donnees-relationnelles\\\/\",\"url\":\"https:\\\/\\\/yosigo.ugr.es\\\/fr\\\/etiquette-de-cours\\\/les-bases-de-donnees-relationnelles\\\/\",\"name\":\"bases de datos relacionales archivos - #YoSigoUGR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yosigo.ugr.es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yosigo.ugr.es\\\/fr\\\/etiquette-de-cours\\\/les-bases-de-donnees-relationnelles\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yosigo.ugr.es\\\/fr\\\/etiquette-de-cours\\\/les-bases-de-donnees-relationnelles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/yosigo.ugr.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"bases de datos relacionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yosigo.ugr.es\\\/#website\",\"url\":\"https:\\\/\\\/yosigo.ugr.es\\\/\",\"name\":\"#YoSigoUGR\",\"description\":\"Formaci\u00f3n abierta promovido por el Vicerrectorado de Investigaci\u00f3n y Transferencia y la Escuela Internacional de Posgrado de la UGR\",\"publisher\":{\"@id\":\"https:\\\/\\\/yosigo.ugr.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yosigo.ugr.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/yosigo.ugr.es\\\/#organization\",\"name\":\"#YoSigoUGR\",\"url\":\"https:\\\/\\\/yosigo.ugr.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/yosigo.ugr.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/yosigo.ugr.es\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/yosigo-web-24.png\",\"contentUrl\":\"https:\\\/\\\/yosigo.ugr.es\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/yosigo-web-24.png\",\"width\":250,\"height\":38,\"caption\":\"#YoSigoUGR\"},\"image\":{\"@id\":\"https:\\\/\\\/yosigo.ugr.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"bases de datos relacionales archivos - #YoSigoUGR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yosigo.ugr.es\/it\/etichetta-del-corso\/database-relazionali\/","og_locale":"it_IT","og_type":"article","og_title":"bases de datos relacionales archivos - #YoSigoUGR","og_url":"https:\/\/yosigo.ugr.es\/it\/etichetta-del-corso\/database-relazionali\/","og_site_name":"#YoSigoUGR","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/yosigo.ugr.es\/fr\/etiquette-de-cours\/les-bases-de-donnees-relationnelles\/","url":"https:\/\/yosigo.ugr.es\/fr\/etiquette-de-cours\/les-bases-de-donnees-relationnelles\/","name":"archivi di database relazionali - #YoSigoUGR","isPartOf":{"@id":"https:\/\/yosigo.ugr.es\/#website"},"breadcrumb":{"@id":"https:\/\/yosigo.ugr.es\/fr\/etiquette-de-cours\/les-bases-de-donnees-relationnelles\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/yosigo.ugr.es\/fr\/etiquette-de-cours\/les-bases-de-donnees-relationnelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/yosigo.ugr.es\/"},{"@type":"ListItem","position":2,"name":"bases de datos relacionales"}]},{"@type":"WebSite","@id":"https:\/\/yosigo.ugr.es\/#website","url":"https:\/\/yosigo.ugr.es\/","name":"#YoSigoUGR","description":"Formazione aperta promossa dalla Viceregione per la Ricerca e il Trasferimento e dalla International Graduate School dell'UGR.","publisher":{"@id":"https:\/\/yosigo.ugr.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yosigo.ugr.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/yosigo.ugr.es\/#organization","name":"#YoSigoUGR","url":"https:\/\/yosigo.ugr.es\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/yosigo.ugr.es\/#\/schema\/logo\/image\/","url":"https:\/\/yosigo.ugr.es\/wp-content\/uploads\/2024\/01\/yosigo-web-24.png","contentUrl":"https:\/\/yosigo.ugr.es\/wp-content\/uploads\/2024\/01\/yosigo-web-24.png","width":250,"height":38,"caption":"#YoSigoUGR"},"image":{"@id":"https:\/\/yosigo.ugr.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/yosigo.ugr.es\/it\/wp-json\/wp\/v2\/ld_course_tag\/94","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yosigo.ugr.es\/it\/wp-json\/wp\/v2\/ld_course_tag"}],"about":[{"href":"https:\/\/yosigo.ugr.es\/it\/wp-json\/wp\/v2\/taxonomies\/ld_course_tag"}],"wp:post_type":[{"href":"https:\/\/yosigo.ugr.es\/it\/wp-json\/wp\/v2\/sfwd-courses?ld_course_tag=94"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}